{"id":6568,"date":"2023-12-12T14:02:56","date_gmt":"2023-12-12T13:02:56","guid":{"rendered":"https:\/\/medytec.eu\/?p=6568"},"modified":"2023-12-13T12:47:38","modified_gmt":"2023-12-13T11:47:38","slug":"teledyne-solutions-dimagerie-pour-application-medicale","status":"publish","type":"post","link":"https:\/\/medytec.eu\/fr\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/","title":{"rendered":"TELEDYNE E2V &#8211; Solutions d&rsquo;imagerie pour les applications m\u00e9dicales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6568\" class=\"elementor elementor-6568\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a111971 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a111971\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8af8f62\" data-id=\"8af8f62\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57206bc elementor-widget elementor-widget-text-editor\" data-id=\"57206bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dans le\u00a0<span style=\"color: #00a8bc;\"><a style=\"color: #00a8bc;\" href=\"https:\/\/medytec.eu\/fr\/vos-evenements\/espaces-medytec\/\" target=\"_blank\" rel=\"noreferrer noopener\">showroom<\/a>\u00a0<\/span>de Medytec, nous exposons les solutions et les produits innovants d\u00e9velopp\u00e9s par les entreprises de notre<span style=\"color: #00a8bc;\">\u00a0<a style=\"color: #00a8bc;\" href=\"https:\/\/medytec.eu\/fr\/un-ecosysteme-d-excellence-en-sante\/grenoble-alpes-territoire-pionnier\/\" target=\"_blank\" rel=\"noreferrer noopener\">territoire<\/a><\/span>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd6b3d elementor-widget elementor-widget-image\" data-id=\"6cd6b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"52\" src=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo-300x52.png\" class=\"attachment-medium size-medium wp-image-6656\" alt=\"\" srcset=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo-300x52.png 300w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo-1024x177.png 1024w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo-768x132.png 768w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo-18x3.png 18w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-e2v-Logo.png 1142w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d22d325 elementor-widget elementor-widget-spacer\" data-id=\"d22d325\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea69178 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea69178\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-30919bf\" data-id=\"30919bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9271afe elementor-widget elementor-widget-image\" data-id=\"9271afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-1024x768.jpg\" class=\"attachment-large size-large wp-image-6612\" alt=\"\" srcset=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-1024x768.jpg 1024w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-300x225.jpg 300w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-768x576.jpg 768w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-1536x1152.jpg 1536w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-2048x1536.jpg 2048w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/vitrine-teledyne-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-dc0492a\" data-id=\"dc0492a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2858cac elementor-widget elementor-widget-text-editor\" data-id=\"2858cac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teledyne e2v<\/strong> est une entreprise de<strong> semi-conducteurs <\/strong>bas\u00e9e \u00e0 Saint-\u00c9gr\u00e8ve, Grenoble et cr\u00e9\u00e9e en <strong>1955<\/strong> sous le nom de Thomson. La soci\u00e9t\u00e9 fait partie du groupe Teledyne Imaging, regroupant des entreprises de pointe align\u00e9es sous l&rsquo;ombrelle de Teledyne. Fortes d\u2019une <strong>expertise in\u00e9gal\u00e9e<\/strong>, les entit\u00e9s de Teledyne Imaging offrent une technologie de premier plan et des capacit\u00e9s exceptionnelles dans le domaine de la d\u00e9t\u00e9ction et de la synth\u00e8se.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ec2863 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ec2863\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de55b33\" data-id=\"de55b33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29f78b2 elementor-widget elementor-widget-spacer\" data-id=\"29f78b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8561c3 elementor-widget elementor-widget-heading\" data-id=\"e8561c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Le d\u00e9veloppement en imagerie : c\u0153ur de m\u00e9tier<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85afee5 elementor-widget elementor-widget-text-editor\" data-id=\"85afee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teledyne e2v,<\/strong> par son savoir-faire, se positionne au c\u0153ur de <strong>l\u2019industrie des semi-conducteurs<\/strong> en concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants. Ces composants sont la pierre angulaire de nombreuses applications, de modules \u00e9lectroniques \u00e0 des syst\u00e8mes de cam\u00e9ras sophistiqu\u00e9s et des capteurs dentaires avanc\u00e9s. Gr\u00e2ce \u00e0 son \u00e9quipe de <strong>concepteurs exp\u00e9riment\u00e9s<\/strong>, <strong>Teledyne e2v<\/strong> intervient dans le design des puces, la conception de cartes \u00e9lectroniques, la conception m\u00e9canique, jusqu\u2019au logiciels embarqu\u00e9s.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e6849 elementor-widget elementor-widget-image\" data-id=\"e7e6849\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-1024x576.png\" class=\"attachment-large size-large wp-image-6642\" alt=\"\" srcset=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-1024x576.png 1024w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-300x169.png 300w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-768x432.png 768w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-1536x864.png 1536w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-18x10.png 18w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging-800x450.png 800w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Digital-imaging.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-831d436 elementor-widget elementor-widget-spacer\" data-id=\"831d436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec54d41 elementor-widget elementor-widget-heading\" data-id=\"ec54d41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Des moyens de production pouss\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdf2177 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdf2177\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bac67fe\" data-id=\"bac67fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-974da70 elementor-widget elementor-widget-text-editor\" data-id=\"974da70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Teledyne e2v<\/strong>, c\u2019est actuellement\u00a0<strong>2000 m2 de salle blanche,<\/strong>\u00a0dont 1100 m2 r\u00e9nov\u00e9s (GECkO 1 et 2) ainsi que 200 m2 qui seront r\u00e9nov\u00e9s en 2024 et 700 m2 pour de futures applications. Les classes de propret\u00e9 ISO vont de la classe 6 (la moins stricte) \u00e0 la classe 4 (la plus stricte), garantissant un <strong>environnement de production impeccable<\/strong>. La soci\u00e9t\u00e9 dispose de lignes de production d\u00e9di\u00e9es \u00e0 l\u2019assemblage de capteurs d\u2019images, capteurs intraoraux dentaires et de cam\u00e9ras. Chaque installation est \u00e9quip\u00e9e de bancs de test afin de r\u00e9pondre aux normes de qualit\u00e9 les plus strictes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6518ad4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6518ad4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf439e3\" data-id=\"cf439e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5576e57 elementor-widget elementor-widget-image\" data-id=\"5576e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"355\" src=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Salle-blanche-robot-1-768x355.png\" class=\"attachment-medium_large size-medium_large wp-image-6640\" alt=\"\" srcset=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Salle-blanche-robot-1-768x355.png 768w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Salle-blanche-robot-1-300x139.png 300w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Salle-blanche-robot-1-18x8.png 18w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Salle-blanche-robot-1.png 792w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b4cb1f\" data-id=\"6b4cb1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146ba5f elementor-widget elementor-widget-text-editor\" data-id=\"146ba5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avec des capacit\u00e9s <strong>d\u2019assemblage \u00e0 la fois manuel et automatis\u00e9,<\/strong> Teledyne e2v offre une <strong>flexibilit\u00e9<\/strong> <strong>exceptionnelle<\/strong> pour r\u00e9pondre \u00e0 la vari\u00e9t\u00e9 de besoins et exigences des diff\u00e9rents clients. Tous les composants sont d\u00e9velopp\u00e9s et produits conform\u00e9ment \u00e0 la norme ISO 13485.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dff6a4 elementor-widget elementor-widget-spacer\" data-id=\"2dff6a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7e03d elementor-widget elementor-widget-heading\" data-id=\"1e7e03d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">De la collaboration \u00e0 l\u2019innovation : r\u00e9inventer l\u2019imagerie m\u00e9dicale<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60256a3 elementor-widget elementor-widget-text-editor\" data-id=\"60256a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les capteurs offrent une couverture du spectre du rayon X, en passant par le visible et en allant jusqu\u2019au proche infrarouge<strong>. <\/strong>Depuis la fin des <b>ann\u00e9es <\/b>1980, nous avons d\u00e9velopp\u00e9 <strong>5 g\u00e9n\u00e9rations de capteurs intraoraux dentaires <\/strong>en commen\u00e7ant par des capteurs utilisant la technologie CCD puis en transitionnant \u00e0 des capteurs utilisant la technologie CMOS. Nous avons par ailleurs, r\u00e9cemment lanc\u00e9 une <strong>nouvelle gamme de<\/strong> <strong>capteurs intraoraux<\/strong> r\u00e9pondant aux besoins de nos clients partenaires recherchant une forte diff\u00e9rentiation pour leurs clients que sont les<strong> cabinets dentaires.<\/strong> Ces produits minimisent la dose de rayons X utilis\u00e9s pour r\u00e9aliser des radiographies dentaires \u00e0 l\u2019int\u00e9rieur de la cavit\u00e9 buccale, tout en conservant une qualit\u00e9 optimale de l\u2019image permettant le diagnostic.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf2a87 elementor-widget elementor-widget-image\" data-id=\"ebf2a87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5.png\" class=\"attachment-full size-full wp-image-6638\" alt=\"\" srcset=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5.png 1920w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-300x169.png 300w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-1024x576.png 1024w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-768x432.png 768w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-1536x864.png 1536w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-18x10.png 18w, https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-5-800x450.png 800w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4738194 elementor-widget elementor-widget-text-editor\" data-id=\"4738194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De plus, <strong>Teledyne e2v<\/strong> est <strong>leader mondial <\/strong>depuis plus de 15 ans dans la <strong>fourniture de cam\u00e9ras<\/strong> permettant de r\u00e9aliser des images de la r\u00e9tine lors d&rsquo;une OCT (Optical Coherence Tomography) Celles-ci sont int\u00e9gr\u00e9es par les clients dans leurs dispositifs m\u00e9dicaux \u00e0 destination des ophtalmologues.\u00a0 Ainsi, <strong>Teledyne e2v<\/strong> b\u00e9n\u00e9ficie d\u2019un solide ancrage sur le march\u00e9 de <strong>l&rsquo;ophtalmologie<\/strong>. Ce succ\u00e8s durable repose sur une technologie innovante et brevet\u00e9e qui r\u00e9volutionne le domaine de l&rsquo;imagerie r\u00e9tinienne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a114c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"00a114c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e10b741 elementor-widget elementor-widget-text-editor\" data-id=\"e10b741\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au cours des six derni\u00e8res ann\u00e9es, <strong>Teledyne e2v<\/strong> a \u00e9galement \u00e9tendu son expertise en collaborant avec les principaux acteurs du <strong>march\u00e9 des endoscopes<\/strong> afin d\u2019innover dans le domaine de la capture d\u2019images m\u00e9dicales. <strong>Teledyne e2v<\/strong> propose des capteurs <strong>tr\u00e8s miniaturis\u00e9s<\/strong>, disposant des meilleures caract\u00e9ristiques pour \u00eatre ins\u00e9r\u00e9s dans des endoscopes flexibles et rigides. Ces \u00e9quipements permettent de fournir au corps m\u00e9dical des images d\u00e9taill\u00e9es ainsi que des diagnostiques tr\u00e8s pr\u00e9cis lors de chirurgies mini-invasives.<\/p><p>Tout en poursuivant sa qu\u00eate d\u2019excellence technologique, <strong>Teledyne e2v<\/strong> offre \u00e0 ses clients souplesse et flexibilit\u00e9 sur l&rsquo;ensemble de sa cha\u00eene d&rsquo;approvisionnement et garantie la disponibilit\u00e9 \u00e0 long terme du produit. Ainsi, <strong>Teledyne e2v<\/strong> est en mesure de fournir \u00e0 ses clients une solution d&rsquo;imagerie num\u00e9rique compl\u00e8te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-802b387 elementor-widget elementor-widget-heading\" data-id=\"802b387\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chiffres et informations cl\u00e9s*<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbf5a98 elementor-widget elementor-widget-text-editor\" data-id=\"fbf5a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>1980<\/strong> : Cr\u00e9ation du premier capteur dentaire<\/li><li><strong>1997-2000\u00a0<\/strong>: Cr\u00e9ation de la premi\u00e8re cam\u00e9ra OCT\u00a0<\/li><li><strong>2017<\/strong> : Premi\u00e8re conception de capteurs personnalis\u00e9s pour l&rsquo;endoscopie.<\/li><li><strong>253 employ\u00e9s<\/strong> aujourd\u2019hui en 2023<\/li><li>Plus de <strong>200 clients<\/strong> dans le monde<\/li><li>Plus de <strong>400 brevets<\/strong> actifs<\/li><\/ul><h6><em>*updated in July 2023<\/em><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddcd705 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ddcd705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.teledyne-e2v.com\/en-us\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bf8240 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bf8240\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0ff414\" data-id=\"b0ff414\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f51617 elementor-widget elementor-widget-text-editor\" data-id=\"9f51617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/27a1.svg\" alt=\"\u27a1\" \/>\u00a0Venez d\u00e9couvrir les innovations du showroom de Medytec lors de nos<span style=\"color: #00a8bc;\"><strong>\u00a0<a style=\"color: #00a8bc;\" href=\"https:\/\/medytec.eu\/fr\/events\/journees-libre-acces-showroom-medytec\/\" target=\"_blank\" rel=\"noopener\">portes ouvertes<\/a><\/strong>\u00a0!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3812791 elementor-widget elementor-widget-text-editor\" data-id=\"3812791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/medytec.eu\/fr\/2023\/03\/14\/les-innovations-en-sante-du-territoire-quand-lia-decrypte-les-images-du-cerveau\/\" target=\"_blank\" rel=\"noopener\">Des outils d\u2019aide \u00e0 la d\u00e9cision clinique pour la radiologie \u2013 Pixyl <\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/10\/05\/les-innovations-en-sante-du-territoire-pi-box-innospark-calculs-renaux\/\">Les Pi-Box\u00a9, collecte de calculs r\u00e9naux<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/07\/08\/les-innovations-en-sante-du-territoire-le-labpad-d-avalun\/\" target=\"_blank\" rel=\"noopener\">Le Labpad<\/a><a href=\"https:\/\/medytec.eu\/fr\/2020\/12\/03\/les-innovations-en-sante-du-territoire-les-dispositifs-intuity-ject-mix\/\" target=\"_blank\" rel=\"noopener\">\u00ae<\/a><a href=\"https:\/\/medytec.eu\/fr\/2021\/07\/08\/les-innovations-en-sante-du-territoire-le-labpad-d-avalun\/\" target=\"_blank\" rel=\"noopener\">\u00a0de Avalun\u00a0<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/04\/08\/les-innovations-en-sante-du-territoire-la-technologie-de-steute\/\" target=\"_blank\" rel=\"noopener\">Les p\u00e9dales de Steute<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2020\/12\/03\/les-innovations-en-sante-du-territoire-les-dispositifs-intuity-ject-mix\/\" target=\"_blank\" rel=\"noopener\">Les dispositifs Intuity\u00ae Ject &amp; Mix<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/01\/05\/les-innovations-en-sante-du-territoire-le-dispositif-de-neurostimulation-transcutanee-connecte-actitens\/\" target=\"_blank\" rel=\"noreferrer noopener\">Le dispositif de neurostimulation transcutan\u00e9e connect\u00e9 actiTENS<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/2020\/07\/10\/decouvrez-les-innovations-en-sante-du-territoire-le-dispositif-protool\/\">Le dispositif PROTOOL\u00ae<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/2020\/08\/17\/les-innovations-en-sante-du-territoire-la-micro-fabrication-2d-et-3d\/\">La micro fabrication 2D et 3D<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2020\/09\/23\/les-innovations-en-sante-du-territoire-le-pansement-connecte\/\">Le pansement connect\u00e9 de Grapheal<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/03\/11\/les-innovations-en-sante-du-territoire-la-solution-remedee-labs\/\" target=\"_blank\" rel=\"noopener\">La solution Remedee Labs pour la prise en charge de la douleur<\/a><\/li><li><a href=\"https:\/\/medytec.eu\/fr\/2021\/02\/11\/les-innovations-en-sante-du-territoire-la-plateforme-surgivisio-decential-robotics\/\" target=\"_blank\" rel=\"noreferrer noopener\">La plateforme Surgivisio d\u2019eCential Robotics<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a1dda elementor-widget elementor-widget-text-editor\" data-id=\"e4a1dda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\">L&rsquo;\u00e9quipe Medytec<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dans le\u00a0showroom\u00a0de Medytec, nous exposons les solutions et les produits innovants d\u00e9velopp\u00e9s par les entreprises de notre\u00a0territoire. Teledyne e2v est une entreprise de semi-conducteurs bas\u00e9e \u00e0 Saint-\u00c9gr\u00e8ve, Grenoble et cr\u00e9\u00e9e en 1955 sous le nom de Thomson. La soci\u00e9t\u00e9 fait partie du groupe Teledyne Imaging, regroupant des entreprises de pointe align\u00e9es sous l&rsquo;ombrelle de Teledyne. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[55,56],"tags":[],"class_list":["post-6568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovations-en-sante","category-partenariats","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teledyne e2v, solution d&#039;imagerie pour les applications m\u00e9dicales<\/title>\n<meta name=\"description\" content=\"Teledyne e2v au c\u0153ur de l&#039;industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medytec.eu\/fr\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teledyne e2v, solution d&#039;imagerie pour les applications m\u00e9dicales\" \/>\n<meta property=\"og:description\" content=\"Teledyne e2v au c\u0153ur de l&#039;industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medytec.eu\/fr\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/\" \/>\n<meta property=\"og:site_name\" content=\"Medytec\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-12T13:02:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-13T11:47:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"okparfait\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"okparfait\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/\"},\"author\":{\"name\":\"okparfait\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/#\\\/schema\\\/person\\\/52643406ade6747ec29f0a5ca286f5fe\"},\"headline\":\"TELEDYNE E2V &#8211; Solutions d&rsquo;imagerie pour les applications m\u00e9dicales\",\"datePublished\":\"2023-12-12T13:02:56+00:00\",\"dateModified\":\"2023-12-13T11:47:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/\"},\"wordCount\":880,\"publisher\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Teledyne-6.png\",\"articleSection\":[\"Innovations en sant\u00e9\",\"Partenariats\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/\",\"url\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/\",\"name\":\"Teledyne e2v, solution d'imagerie pour les applications m\u00e9dicales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Teledyne-6.png\",\"datePublished\":\"2023-12-12T13:02:56+00:00\",\"dateModified\":\"2023-12-13T11:47:38+00:00\",\"description\":\"Teledyne e2v au c\u0153ur de l'industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Teledyne-6.png\",\"contentUrl\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Teledyne-6.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/2023\\\/12\\\/12\\\/teledyne-solutions-dimagerie-pour-application-medicale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/medytec.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TELEDYNE E2V &#8211; Solutions d&rsquo;imagerie pour les applications m\u00e9dicales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/#website\",\"url\":\"https:\\\/\\\/medytec.eu\\\/\",\"name\":\"Medytec\",\"description\":\"Le hub des technologies de la sant\u00e9 de grenoble-Alpes\",\"publisher\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medytec.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/#organization\",\"name\":\"MedYtec\",\"url\":\"https:\\\/\\\/medytec.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-medytec.png\",\"contentUrl\":\"https:\\\/\\\/medytec.eu\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo-medytec.png\",\"width\":426,\"height\":147,\"caption\":\"MedYtec\"},\"image\":{\"@id\":\"https:\\\/\\\/medytec.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medytec.eu\\\/#\\\/schema\\\/person\\\/52643406ade6747ec29f0a5ca286f5fe\",\"name\":\"okparfait\",\"url\":\"https:\\\/\\\/medytec.eu\\\/fr\\\/author\\\/e486db832ef7dcb5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teledyne e2v, solution d'imagerie pour les applications m\u00e9dicales","description":"Teledyne e2v au c\u0153ur de l'industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medytec.eu\/fr\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/","og_locale":"fr_FR","og_type":"article","og_title":"Teledyne e2v, solution d'imagerie pour les applications m\u00e9dicales","og_description":"Teledyne e2v au c\u0153ur de l'industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0","og_url":"https:\/\/medytec.eu\/fr\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/","og_site_name":"Medytec","article_published_time":"2023-12-12T13:02:56+00:00","article_modified_time":"2023-12-13T11:47:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png","type":"image\/png"}],"author":"okparfait","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"okparfait","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#article","isPartOf":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/"},"author":{"name":"okparfait","@id":"https:\/\/medytec.eu\/#\/schema\/person\/52643406ade6747ec29f0a5ca286f5fe"},"headline":"TELEDYNE E2V &#8211; Solutions d&rsquo;imagerie pour les applications m\u00e9dicales","datePublished":"2023-12-12T13:02:56+00:00","dateModified":"2023-12-13T11:47:38+00:00","mainEntityOfPage":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/"},"wordCount":880,"publisher":{"@id":"https:\/\/medytec.eu\/#organization"},"image":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#primaryimage"},"thumbnailUrl":"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png","articleSection":["Innovations en sant\u00e9","Partenariats"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/","url":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/","name":"Teledyne e2v, solution d'imagerie pour les applications m\u00e9dicales","isPartOf":{"@id":"https:\/\/medytec.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#primaryimage"},"image":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#primaryimage"},"thumbnailUrl":"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png","datePublished":"2023-12-12T13:02:56+00:00","dateModified":"2023-12-13T11:47:38+00:00","description":"Teledyne e2v au c\u0153ur de l'industrie des semi-conducteurs concevant des circuits int\u00e9gr\u00e9s de pointe et des sous-syst\u00e8mes innovants.\u00a0","breadcrumb":{"@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#primaryimage","url":"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png","contentUrl":"https:\/\/medytec.eu\/wp-content\/uploads\/2023\/12\/Teledyne-6.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/medytec.eu\/2023\/12\/12\/teledyne-solutions-dimagerie-pour-application-medicale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/medytec.eu\/"},{"@type":"ListItem","position":2,"name":"TELEDYNE E2V &#8211; Solutions d&rsquo;imagerie pour les applications m\u00e9dicales"}]},{"@type":"WebSite","@id":"https:\/\/medytec.eu\/#website","url":"https:\/\/medytec.eu\/","name":"Medytec","description":"Le hub des technologies de la sant\u00e9 de grenoble-Alpes","publisher":{"@id":"https:\/\/medytec.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medytec.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/medytec.eu\/#organization","name":"MedYtec","url":"https:\/\/medytec.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/medytec.eu\/#\/schema\/logo\/image\/","url":"https:\/\/medytec.eu\/wp-content\/uploads\/2020\/02\/logo-medytec.png","contentUrl":"https:\/\/medytec.eu\/wp-content\/uploads\/2020\/02\/logo-medytec.png","width":426,"height":147,"caption":"MedYtec"},"image":{"@id":"https:\/\/medytec.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/medytec.eu\/#\/schema\/person\/52643406ade6747ec29f0a5ca286f5fe","name":"okparfait","url":"https:\/\/medytec.eu\/fr\/author\/e486db832ef7dcb5\/"}]}},"_links":{"self":[{"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/posts\/6568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/comments?post=6568"}],"version-history":[{"count":0,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/posts\/6568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/media\/6658"}],"wp:attachment":[{"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/media?parent=6568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/categories?post=6568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medytec.eu\/fr\/wp-json\/wp\/v2\/tags?post=6568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}